{"id":1517,"date":"2025-05-23T09:33:52","date_gmt":"2025-05-23T07:33:52","guid":{"rendered":"https:\/\/format.testing-reizwerk.com\/?page_id=1517"},"modified":"2025-09-02T13:58:02","modified_gmt":"2025-09-02T11:58:02","slug":"agb","status":"publish","type":"page","link":"https:\/\/www.formatsoftware.de\/de\/agb\/","title":{"rendered":"AGB"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section class=\"hero hero--noimage  dark\" \n                style=\"background-color: ; \">\n         <div class=\"container-fluid hero__container\">\n            <div class=\"grid__row hero__row\">\n                <div class=\"grid__item col-12 col-md-6\">\n                                    <\/div>\n                <div class=\"grid__item col-12 col-md-6\">\n                    <div class=\"hero__content\">\n                        <h1 class=\"hero__header title title--bold\">\n                            Allgemeine Gesch\u00e4ftsbedingungen der FORMAT Software Service GmbH                                                    <\/h1>\n                        \n                        <div class=\"hero__text\"><p>(im Folgenden: FORMAT)<\/p><\/p>\n<\/div>                           \n                    <\/div>\n                <\/div>\n            <\/div>\n         <\/div>\n        <\/section>    \n\t\t[vc_section element_spacing=&#8220;space&#8211;large&#8220;][vc_row][vc_column][vc_column_text]<\/p>\n<h2>\u00a7 1 Geltungsbereich<\/h2>\n<p>(1) Die nachstehenden Allgemeinen Gesch\u00e4ftsbedingungen (AGB) gelten f\u00fcr alle &#8211; auch zuk\u00fcnftige &#8211; Gesch\u00e4ftsbeziehungen zwischen der FORMAT und ihren Kunden. Dies gilt auch dann, wenn die FORMAT in Kenntnis entgegenstehender oder abweichender Bedingungen des Kunden Lieferungen oder Leistungen an den Kunden vorbehaltlos ausf\u00fchrt.<\/p>\n<p>(2) Vertragsbedingungen des Kunden finden auf diese Gesch\u00e4ftsbeziehungen keine Anwendung, es sei denn, sie werden ausnahmsweise von der FORMAT ausdr\u00fccklich schriftlich anerkannt. Im \u00dcbrigen wird deren Geltung hiermit auch f\u00fcr die Zukunft widersprochen. Schweigen der FORMAT zu Geltungsverweisen des Kunden auf dessen Vertragsbedingungen gilt nicht als Zustimmung.<\/p>\n<p>(3) Prospekte, Beschreibungen und Abbildungen der Leistungen der FORMAT sind vorbehaltlich der ausdr\u00fccklichen Einbeziehung in das Vertragsverh\u00e4ltnis der Parteien unverbindlich. Ihre \u00c4nderung bleibt vorbehalten.<\/p>\n<p>(4) Die Leistungsangebote der FORMAT richten sich ausdr\u00fccklich nicht an Verbraucher im Sinne des \u00a7 13 BGB. Vertr\u00e4ge mit Verbrauchern schlie\u00dft die FORMAT daher nicht ab.[\/vc_column_text][vc_column_text]<\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 2 Vertragsabschluss und Vertragsanbahnung<\/h2>\n<p>(1) Vertr\u00e4ge zwischen FORMAT und ihren Kunden bed\u00fcrfen zu ihrer Wirksamkeit der Schriftform. Im Falle einer vom Kunden \u00fcbermittelten Bestellung kommt der Vertrag mit der schriftlichen Auftragsbest\u00e4tigung von FORMAT zustande. Erfolgt die Auftragsbest\u00e4tigung elektronisch, gen\u00fcgt f\u00fcr die Schriftform auch eine E-Mail mit elektronischer Signatur. Auf die Regelungen des \u00a7 11 Absatz 1 wird verwiesen.<\/p>\n<p>(2) Alle von der FORMAT erstellten Angebote sind freibleibend und unverbindlich, soweit im jeweiligen Angebot nicht ausdr\u00fccklich etwas Anderweitiges bestimmt ist.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 3 Lieferfristen und Liefertermine<\/h2>\n<p>Lieferfristen und -termine sind vorbehaltlich ausdr\u00fccklicher anderweitiger Vereinbarung unverbindlich. Soweit durch FORMAT eine als verbindlich vereinbarte Lieferfrist um mehr als vier Wochen \u00fcberschritten wird, kann der Kunde FORMAT eine weitere Nachfrist von vier Wochen, beginnend mit dem Eingang der Fristsetzung bei FORMAT, setzen, nach deren fruchtlosem Ablauf der Kunde durch eingeschriebenen Brief oder eine elektronische Nachricht mit qualifizierter elektronischer Signatur vom Vertrag zur\u00fccktreten kann.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 4 Preise, Zahlungsbedingungen, Anpassungsvorbehalt und Storno-Regelung<\/h2>\n<p>(1) Die in der schriftlichen Auftragsbest\u00e4tigung der FORMAT gem\u00e4\u00df \u00a7 2 Absatz 1 genannten Preise gelten vorbehaltlich ausdr\u00fccklicher abweichender Vereinbarungen ab Versendungsort zuz\u00fcglich Verpackungs-, Fracht- und Versandkosten.<\/p>\n<p>(2) F\u00fcr die Leistungen der FORMAT gelten im \u00dcbrigen, vorbehaltlich ausdr\u00fccklich abweichender anderweitiger Vereinbarungen, die bei Vertragsabschluss jeweils aktuellen Preise, insbesondere f\u00fcr Lizenzentgelte, Pflegegeb\u00fchren und Dienstleistungs-Stundens\u00e4tze.<\/p>\n<p>(3) Der FORMAT bleibt vorbehalten, die Preise und Entgelte wegen eingetretener Kostensteigerungen (z.B. erh\u00f6hter Personalaufwand in Folge gestiegener gesetzlicher und technischer Anforderungen, erh\u00f6hte Lizenzgeb\u00fchren Dritter f\u00fcr Software, erh\u00f6hte Beschaffungskosten) anzupassen. Die FORMAT wird bei Anpassungen auch etwaige Kostenminderungen angemessen ber\u00fccksichtigen und die entsprechenden \u00c4nderungen gegen\u00fcber dem Kunden transparent darlegen, ohne aber zur Offenlegung ihrer Kalkulation verpflichtet zu sein. F\u00fchrt die Anpassung zu einer Preiserh\u00f6hung von mehr als 5 % (netto) des bisherigen Preises, so kann der Kunde den betroffenen Vertrag vorzeitig k\u00fcndigen. Die FORMAT k\u00fcndigt derartige Preisanpassungen so rechtzeitig an, dass der Kunde unter Einhaltung der vertraglich vereinbarten K\u00fcndigungsfrist das Vertragsverh\u00e4ltnis vor Geltung der Anpassung beenden kann. \u00dcbt der Kunde dieses K\u00fcndigungsrecht nicht fristgerecht aus, wird die Preisanpassung verbindlich.<\/p>\n<p>(4) Die von der FORMAT angegebenen Preise sind Nettopreise in EURO, zuz\u00fcglich Mehrwertsteuer in der jeweiligen gesetzlichen H\u00f6he.<\/p>\n<p>(5) Softwarepreise verstehen sich ohne Dienstleistungen und eventuelle Anpassung an Hardware oder andere Software. Diese und \u00e4hnliche Leistungen sind vorbehaltlich ausdr\u00fccklich abweichender anderweitiger Vereinbarungen vom Kunden gesondert zu bestellen und gem\u00e4\u00df den bei Vertragsabschluss jeweils aktuellen Preisen zu verg\u00fcten.<\/p>\n<p>(6) Alle Rechnungen der FORMAT sind, soweit nicht anders vereinbart, innerhalb zehn Tagen ab Rechnungsdatum und ohne jeden Abzug zu zahlen.<\/p>\n<p>(7) Eine Stornierung von Schulungen oder Beratungsleistungen durch den Kunden ist bis vier Wochen vor dem vereinbarten Termin ohne Kosten m\u00f6glich. Danach betragen bis zu zwei Wochen vor dem vereinbarten Termin die Storno-Geb\u00fchren 50% der vereinbarten Verg\u00fctung, bis zu einer Woche vor dem vereinbarten Termin 75% der vereinbarten Verg\u00fctung. Erfolgt die Stornierung nach diesem Zeitpunkt, wird die volle Verg\u00fctung f\u00e4llig. Schon angefallene Kosten und Auslagen f\u00fcr Reisen zum Schulungs- oder Beratungsort sind vom Kunden in voller H\u00f6he zu tragen.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 5 Rechtsfolgen von Pflichtverletzungen, Mitwirkungspflichten des Kunden<\/h2>\n<p>(1) Im Falle erheblicher Abweichungen von der vertraglich geschuldeten Leistung (Gew\u00e4hrleistungsfall) ist die FORMAT nach ihrer Wahl zur Nachbesserung oder Ersatzlieferung berechtigt und, soweit diese nicht mit unangemessenem Aufwand verbunden ist, auch verpflichtet. Gelingt es der FORMAT innerhalb einer angemessenen Frist nicht, durch Nachbesserung oder Ersatzlieferung die erheblichen Abweichungen von der Leistungsbeschreibung zu beseitigen oder so zu umgehen, dass dem Kunden eine zumutbare vertragsgem\u00e4\u00dfe Nutzung des Programms erm\u00f6glicht wird, kann der Kunde eine Herabsetzung der Verg\u00fctung verlangen oder vom Vertrag zur\u00fccktreten.<\/p>\n<p>(2) Die M\u00e4ngelanspr\u00fcche nach Absatz 1 erstrecken sich nicht auf M\u00e4ngel, die durch das Abweichen des Kunden vom vertragsgem\u00e4\u00dfen Gebrauch und von den in der Leistungsbeschreibung angegebenen Einsatzbedingungen verursacht werden.<\/p>\n<p>(3) Von der FORMAT dem Kunden gelieferte EDV-Programme \u00fcberpr\u00fcft der Kunde unverz\u00fcglich auf ihre ordnungsgem\u00e4\u00dfe Funktion, insbesondere im Hinblick auf Korrektheit der mit diesen Programmen erzielten Arbeitsergebnisse. Diese Ergebniskontrolle setzt der Kunde w\u00e4hrend der Nutzungsdauer dieser Programme zumindest stichprobenartig sukzessive und regelm\u00e4\u00dfig fort. Der Kunde ist verpflichtet, der FORMAT nachpr\u00fcfbare Unterlagen \u00fcber Art und Auftreten von Abweichungen von der Leistungsbeschreibung zur Verf\u00fcgung zu stellen, sobald er solche feststellt.<\/p>\n<p>(4) F\u00fcr Sch\u00e4den des Kunden (Haftungsfall), die von der FORMAT, ihren Mitarbeitern, gesetzlichen Vertretern oder sonstigen Erf\u00fcllungsgehilfen vors\u00e4tzlich oder grob fahrl\u00e4ssig verursacht werden, haftet die FORMAT unbegrenzt.<\/p>\n<p>(5) Die FORMAT haftet ferner f\u00fcr Sch\u00e4den des Kunden an Leben, K\u00f6rper oder Gesundheit, die die FORMAT, ihre Mitarbeiter, gesetzliche Vertreter oder sonstige Erf\u00fcllungsgehilfen zu vertreten haben.<\/p>\n<p>(6) Die FORMAT haftet gegen\u00fcber dem Kunden auch in F\u00e4llen zwingender Produkthaftung.<\/p>\n<p>(7) Verletzt die FORMAT wesentliche Vertragspflichten (beispielsweise die Belieferung des Kunden mit vertragsgegenst\u00e4ndlicher Software oder die vertragsgem\u00e4\u00dfe Erbringung vereinbarter Dienstleistungen), so haftet sie auch bei leichter Fahrl\u00e4ssigkeit, jedoch beschr\u00e4nkt auf typische voraussehbare Sach- und<br \/>\nVerm\u00f6genssch\u00e4den des Kunden. Die Haftung ist hierbei ausgeschlossen f\u00fcr dem Kunden entgangenen Gewinn, beim Kunden nicht eingetretene Einsparungen, mittelbare Sch\u00e4den sowie f\u00fcr Sch\u00e4den, die ihre Ursache in der vom Kunden oder von Dritten zur Verf\u00fcgung gestellten Anwendungsumgebung oder einer<br \/>\nVerletzung der Pflichten des Kunden aus vorstehendem Absatz 3 haben. Gleiches gilt, wenn von der FORMAT gelieferte Datenverarbeitungsprogramme und darin enthaltene Datenbest\u00e4nde nicht in einer von der FORMAT gelieferten, unver\u00e4nderten Originalfassung oder unter anderen als in der zugeh\u00f6rigen Leistungsbeschreibung<br \/>\nangegebenen Einsatzbedingungen genutzt werden, es sei denn, der Kunde weist nach, dass dies nicht schadensurs\u00e4chlich ist.<\/p>\n<p>(8) Die Haftung f\u00fcr Datenverluste wird auf den typischen Wiederherstellungsaufwand beschr\u00e4nkt, der bei regelm\u00e4\u00dfiger und gefahrentsprechender Anfertigung von Sicherungskopien eingetreten w\u00e4re.<\/p>\n<p>(9) FORMAT haftet nicht f\u00fcr Sch\u00e4den, die auf fehlerhaften Daten, Parametern oder Variablen beruhen, die von dritter Seite (etwa den Zollbeh\u00f6rden) zur Verf\u00fcgung gestellt werden und deren Fehlerhaftigkeit nicht offensichtlich ist.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 6 Beratungs- und Organisationsleistungen<\/h2>\n<p>(1) Erbringt die FORMAT Beratungsleistungen im Zoll- und Au\u00dfenhandel oder f\u00fchrt sie Analyse- und Projektberatungen durch, so stellt dies keine rechtsverbindlichen Leistungen dar. Es handelt sich insoweit um Empfehlungen auf der Grundlage vorhandenen Fachwissens und vorhandener fachlicher Erfahrung. Die Entscheidung zur Annahme dieser Empfehlungen liegt allein beim Kunden.<\/p>\n<p>(2) Beanstandungen der Leistungen gem\u00e4\u00df Absatz 1 sind vom Kunden innerhalb von vier Wochen nach Bekanntgabe oder \u00dcbergabe der Leistung oder bei versteckten M\u00e4ngeln nach deren Entdeckung in schriftlicher Form vorzunehmen. Dabei sind die Beanstandungen in nachvollziehbarer Form dazulegen und durch erl\u00e4uternde Unterlagen zu belegen. Im \u00dcbrigen gilt \u00a7 5 Absatz 3 Satz 3 entsprechend.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 7 Abnahme von Systemen und Programmierleistungen<\/h2>\n<p>(1) Installiert die FORMAT beim Kunden Standard-Software oder erbringt sie individuelle Programmierleistungen f\u00fcr den Kunden, so erkl\u00e4rt der Kunde sp\u00e4testens vier Wochen nach Installation schriftlich gegen\u00fcber der FORMAT die Abnahme der Leistung oder legt eine nachvollziehbare M\u00e4ngelliste vor. L\u00e4sst der Kunde diese Frist ungenutzt verstreichen, gilt die Leistung als abgenommen. Abweichungen der Leistung bzw. des vertragsgegenst\u00e4ndlichen Systems von der Leistungsbeschreibung, die dessen Brauchbarkeit nur unwesentlich beeintr\u00e4chtigen, berechtigen den Kunden nicht, die Abnahme zu verweigern. Legt der Kunde der FORMAT eine nachvollziehbare M\u00e4ngelliste vor, so behebt die FORMAT von ihr zu vertretende M\u00e4ngel unverz\u00fcglich. Zu von ihr nicht zu vertretenden M\u00e4ngel nimmt die FORMAT unverz\u00fcglich Stellung. Der Kunde ist verpflichtet, die FORMAT bei den M\u00e4ngelbeseitigungsma\u00dfnahmen nach Kr\u00e4ften zu unterst\u00fctzen.<\/p>\n<p>(2) Die FORMAT \u00fcbernimmt keine Gew\u00e4hr daf\u00fcr, dass \u00fcberlassene Software spezielle Erfordernisse des Kunden oder die Tauglichkeit zu einem speziellen Zweck erf\u00fcllt, sofern dies nicht ausdr\u00fccklich vereinbart worden ist.<\/p>\n<p>(3) Der Kunde ist alleinverantwortlich f\u00fcr den korrekten Einsatz der Programme, insbesondere f\u00fcr die Sicherung der mit den betreffenden Programmen be- und verarbeiteten Daten.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 8 Vorbehalt der Rechte<\/h2>\n<p>FORMAT beh\u00e4lt sich grunds\u00e4tzlich das Urheberrecht sowie sonstige gewerbliche Schutzrechte an Leistungsgegenst\u00e4nden wie Software, Dokumentationen, Schaltschemata, Zeichnungen, Entw\u00fcrfen, Beschreibungen, Pl\u00e4nen, Konzeptionen und \u00e4hnlichen Unterlagen vor. Ohne schriftliche Einwilligung von FORMAT d\u00fcrfen diese Dritten nicht zug\u00e4nglich gemacht, vervielf\u00e4ltigt, verbreitet oder bearbeitet werden.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 9 Vertraulichkeit<\/h2>\n<p>(1) Die Parteien verpflichten sich, alle ihnen im Rahmen ihrer Zusammenarbeit bekannt gewordenen oder bekannt werdenden Betriebsgeheimnisse und sonstigen Informationen (im Folgenden: \u201eInformationen\u201c) der jeweils anderen Partei nur f\u00fcr Zwecke ihrer Zusammenarbeit zu verwenden und insbesondere Dritten gegen\u00fcber nicht zu offenbaren oder zug\u00e4nglich zu machen.<\/p>\n<p>(2) Informationen im Sinne des Absatzes 1 sind insbesondere Entwicklungs-, Forschungs-, Planungs- und Fertigungsdaten, Muster, Teile, Zeichnungen und Berechnungen, betriebswirtschaftliche, technische und kalkulatorische Angaben, personenbezogene Daten sowie Know-how, ungeachtet ihrer Form (schriftlich, m\u00fcndlich, elektronisch oder sonstige Art der Kenntnisverschaffung).<\/p>\n<p>(3) Nicht unter die Regelung des Absatzes 1 fallen Informationen, die<\/p>\n<ol style=\"list-style-type: lower-latin;\">\n<li>der jeweils anderen Partei bereits zum Zeitpunkt der Bekanntgabe durch die andere Partei nachweislich bekannt waren;<\/li>\n<li>zum Zeitpunkt ihrer Bekanntgabe durch die jeweils andere Partei bereits \u00f6ffentlich bekannt waren;<\/li>\n<li>nach der Bekanntgabe durch die jeweils andere Partei \u00f6ffentlich bekannt werden, ohne dass dies der Vertragspartner zu vertreten hat;<\/li>\n<li>dem allgemeinen Stand der Technik entsprechen.<\/li>\n<\/ol>\n<p>(4) Die Parteien werden die Verpflichtungen aus Absatz 1 auch ihren Mitarbeitern und im Kontext der Gesch\u00e4ftsbeziehung eventuell eingesetzten Dritten auferlegen.<\/p>\n<p>(5) Soweit nicht ausdr\u00fccklich etwas Abweichendes vereinbart ist, endet diese Vertraulichkeitsverpflichtung drei Jahre nach Beendigung des Vertragsverh\u00e4ltnisses der Parteien.<\/p>\n<p>(6) Die Parteien haften einander bei Verletzungen ihrer Vertraulichkeitspflichten auf Ersatz des hierdurch entstandenen Schadens. Jeder Partei bleibt der Nachweis vorbehalten, dass der Schaden auch ohne diese Verletzung entstanden w\u00e4re.<\/p>\n<p>(7) Die Parteien verpflichten sich f\u00fcr jeden Fall der schuldhaften Verletzung ihrer Vertraulichkeitspflichten zur Zahlung einer Vertragsstrafe in H\u00f6he von Euro 10.000,00 an die jeweils andere Partei. Die Geltendmachung von Schadensersatzanspr\u00fcchen nach Absatz 6 bleibt den Parteien vorbehalten. Die Vertragsstrafe wird auf etwaige Schadensersatzanspr\u00fcche angerechnet.<\/p>\n<p>(8) Die G\u00fcltigkeit des Gesetzes zum Schutz von Gesch\u00e4ftsgeheimnissen (GeschGehG) bleibt unber\u00fchrt.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 10 Datenschutz<\/h2>\n<p>(1) Der Kunde wird darauf hingewiesen, dass die FORMAT personenbezogene Daten in dem Umfang speichert und verarbeitet, als dies im Rahmen des Vertragsverh\u00e4ltnisses erforderlich ist. Eine Weitergabe personenbezogener Daten an Dritte erfolgt dar\u00fcber hinaus nur, soweit hierzu eine gesetzliche Verpflichtung besteht.<\/p>\n<p>(2) Die Parteien verpflichten sich, die bei ihnen mit der Verarbeitung von personenbezogenen Daten befassten Personen mit den f\u00fcr sie ma\u00dfgeblichen Bestimmungen des Datenschutzrechts vertraut zu machen und diese im Sinne des Artikel 5 Absatz 1 DS-GVO und Artikel 28 Absatz 3 lit. b DS-GVO zu verpflichten.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 11 Exportbestimmungen<\/h2>\n<p>(1) Der Kunde wird darauf hingewiesen, dass die Produkte und Leistungen der FORMAT deutschen, europ\u00e4ischen und internationalen Exportbestimmungen unterliegen k\u00f6nnen, die ein Verbot oder eine Restriktion der Ausfuhr dieser Leistungen in bestimmte L\u00e4nder oder deren Weitergabe an bestimmte Personen oder Institutionen enthalten. Der Kunde sichert zu, diese Regeln sorgf\u00e4ltig zu beachten.<\/p>\n<p>(2) Verst\u00f6\u00dft der Kunde gegen die Pflicht aus Absatz 1, ist die FORMAT nach Erlangung der Kenntnis von diesem Versto\u00df berechtigt, den jeweiligen Vertrag mit dem Kunden oder auch die gesamte Vertragsbeziehung mit ihm au\u00dferordentlich zu k\u00fcndigen. Eventuelle Schadensersatzanspr\u00fcche aus dem Rechtsversto\u00df des Kunden f\u00fcr Sch\u00e4den, die der FORMAT dadurch entstehen, bleiben ausdr\u00fccklich vorbehalten.<\/p>\n<p>(3) Absatz 1 und Absatz 2 gelten entsprechend, wenn der Kunde Produkte und Leistungen der FORMAT einsetzt, um seinerseits Produkte oder Leistungen zu erbringen, die wiederum unter Versto\u00df gegen die in Absatz 1 genannten Regeln exportiert oder an Dritte abgegeben werden.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 12 Rechte\u00fcbertragung<\/h2>\n<p>Eine Vertragspartei ist nicht berechtigt, einzelne oder die gesamten Rechte aus Gesch\u00e4ftsbeziehungen zwischen der FORMAT und ihren Kunden, ohne vorherige schriftliche Zustimmung der anderen Partei auf Dritte zu \u00fcbertragen.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 13 Schriftform, Rechtswahl, Gerichtsstand, Erf\u00fcllungsort<\/h2>\n<p>(1) Alle Anzeigen, Erkl\u00e4rungen und K\u00fcndigungen sowie \u00c4nderungen, Erg\u00e4nzungen und die Aufhebung von Gesch\u00e4ftsbeziehungen sowie dieses Schriftformerfordernisses bed\u00fcrfen der Schriftform nach \u00a7 126 BGB oder der elektronischen Form nach \u00a7 126a BGB. Abweichungen davon in Einzelvertr\u00e4gen gehen dieser Regelung vor.<\/p>\n<p>(2) F\u00fcr die Gesch\u00e4ftsbeziehungen der FORMAT zu ihren Kunden gilt ausschlie\u00dflich das Recht der Bundesrepublik Deutschland. Die Anwendung des Wiener UN-\u00dcbereinkommens \u00fcber Vertr\u00e4ge \u00fcber den internationalen Warenkauf ist ausgeschlossen.<\/p>\n<p>(3) F\u00fcr alle Rechtsstreitigkeiten aus diesen Gesch\u00e4ftsbeziehungen wird Darmstadt als Gerichtsstand vereinbart.<\/p>\n<p>(4) Erf\u00fcllungsort f\u00fcr alle Verbindlichkeiten aus diesen Gesch\u00e4ftsbeziehungen ist Dreieich am Main.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 14 \u00c4nderungen der AGB<\/h2>\n<p>(1) \u00c4nderungen dieser Allgemeinen Gesch\u00e4ftsbedingungen macht die FORMAT rechtzeitig durch Bereitstellung auf ihrer Website:\u00a0<a href=\"https:\/\/www.formatsoftware.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.formatsoftware.de<\/a>\u00a0bekannt.<\/p>\n<p>(2) Kunden der FORMAT werden \u00fcber \u00c4nderungen nach Absatz 1 oder einzelner Formularvertr\u00e4ge der FORMAT (etwa des Software-Lizenzvertrags, des Software-Pflegevertrags oder des Vertrags \u00fcber ASP Application-Service-Providing) schriftlich oder per E-Mail informiert. Die \u00c4nderungen gelten als akzeptiert, wenn der Kunde diesen nicht innerhalb von vier Wochen nach Bekanntgabe bzw. E-Mail-Zugang schriftlich widerspricht.<\/p>\n<p>(3) Die Regelungen der Abs\u00e4tze 1 und 2 gelten in F\u00e4llen des \u00a7 4 Absatz 3 entsprechend.[\/vc_column_text][vc_column_text][\/vc_column_text][vc_column_text]<\/p>\n<h2>\u00a7 15 Schlussbestimmungen<\/h2>\n<p>(1) Weicht die FORMAT im Einzelfall aus Kulanz- oder vergleichbaren Gr\u00fcnden von einzelnen Festlegungen dieser Gesch\u00e4ftsbedingungen zugunsten des Kunden ab, so stellt dies f\u00fcr die FORMAT weder einen Verzicht auf die Rechtsposition aus dieser Festlegung dar, noch kann der Kunde daraus irgendwelche Rechte f\u00fcr gleichgelagerte oder \u00e4hnliche F\u00e4lle herleiten.<\/p>\n<p>(2) Sollten einzelne Bestimmungen dieser Allgemeinen Gesch\u00e4ftsbedingungen unwirksam oder undurchf\u00fchrbar sein oder werden, so wird dadurch die Wirksamkeit der Gesch\u00e4ftsbedingungen im \u00dcbrigen nicht ber\u00fchrt.[\/vc_column_text][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column][vc_column_text]Stand: April 2022[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section element_spacing=&#8220;space&#8211;large&#8220;][vc_row][vc_column][vc_column_text] \u00a7 1 Geltungsbereich (1) Die nachstehenden Allgemeinen Gesch\u00e4ftsbedingungen (AGB) gelten f\u00fcr alle &#8211; auch zuk\u00fcnftige &#8211; Gesch\u00e4ftsbeziehungen zwischen der FORMAT und ihren Kunden. Dies gilt auch dann, wenn die FORMAT in Kenntnis entgegenstehender oder abweichender Bedingungen des Kunden Lieferungen oder Leistungen an den Kunden vorbehaltlos ausf\u00fchrt. (2) Vertragsbedingungen des Kunden finden auf diese [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-1517","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AGB - FORMAT Software Service GmbH<\/title>\n<meta name=\"description\" content=\"Alle wichtigen Informationen zu unseren Vertragsbedingungen, Rechten und Pflichten \u2013 klar, verst\u00e4ndlich und transparent.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.formatsoftware.de\/de\/agb\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AGB\" \/>\n<meta property=\"og:description\" content=\"Alle wichtigen Informationen zu unseren Vertragsbedingungen, Rechten und Pflichten \u2013 klar, verst\u00e4ndlich und transparent.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.formatsoftware.de\/de\/agb\/\" \/>\n<meta property=\"og:site_name\" content=\"FORMAT Software Service GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-02T11:58:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/agb\\\/\",\"url\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/agb\\\/\",\"name\":\"AGB - FORMAT Software Service GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/#website\"},\"datePublished\":\"2025-05-23T07:33:52+00:00\",\"dateModified\":\"2025-09-02T11:58:02+00:00\",\"description\":\"Alle wichtigen Informationen zu unseren Vertragsbedingungen, Rechten und Pflichten \u2013 klar, verst\u00e4ndlich und transparent.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/agb\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/agb\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/agb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AGB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/\",\"name\":\"FORMAT Software Service GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/#organization\",\"name\":\"FORMAT Software Service GmbH\",\"url\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.formatsoftware.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/formal-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.formatsoftware.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/formal-logo.svg\",\"caption\":\"FORMAT Software Service GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.formatsoftware.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/format-software-service-gmbh?originalSubdomain=de\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/formatsoftwareservicegmbh\",\"https:\\\/\\\/www.youtube.com\\\/@FORMATSoftwareServiceGmbH\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AGB - FORMAT Software Service GmbH","description":"Alle wichtigen Informationen zu unseren Vertragsbedingungen, Rechten und Pflichten \u2013 klar, verst\u00e4ndlich und transparent.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.formatsoftware.de\/de\/agb\/","og_locale":"de_DE","og_type":"article","og_title":"AGB","og_description":"Alle wichtigen Informationen zu unseren Vertragsbedingungen, Rechten und Pflichten \u2013 klar, verst\u00e4ndlich und transparent.","og_url":"https:\/\/www.formatsoftware.de\/de\/agb\/","og_site_name":"FORMAT Software Service GmbH","article_modified_time":"2025-09-02T11:58:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.formatsoftware.de\/de\/agb\/","url":"https:\/\/www.formatsoftware.de\/de\/agb\/","name":"AGB - FORMAT Software Service GmbH","isPartOf":{"@id":"https:\/\/www.formatsoftware.de\/de\/#website"},"datePublished":"2025-05-23T07:33:52+00:00","dateModified":"2025-09-02T11:58:02+00:00","description":"Alle wichtigen Informationen zu unseren Vertragsbedingungen, Rechten und Pflichten \u2013 klar, verst\u00e4ndlich und transparent.","breadcrumb":{"@id":"https:\/\/www.formatsoftware.de\/de\/agb\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.formatsoftware.de\/de\/agb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.formatsoftware.de\/de\/agb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.formatsoftware.de\/de\/"},{"@type":"ListItem","position":2,"name":"AGB"}]},{"@type":"WebSite","@id":"https:\/\/www.formatsoftware.de\/de\/#website","url":"https:\/\/www.formatsoftware.de\/de\/","name":"FORMAT Software Service GmbH","description":"","publisher":{"@id":"https:\/\/www.formatsoftware.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.formatsoftware.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.formatsoftware.de\/de\/#organization","name":"FORMAT Software Service GmbH","url":"https:\/\/www.formatsoftware.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.formatsoftware.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.formatsoftware.de\/wp-content\/uploads\/2025\/07\/formal-logo.svg","contentUrl":"https:\/\/www.formatsoftware.de\/wp-content\/uploads\/2025\/07\/formal-logo.svg","caption":"FORMAT Software Service GmbH"},"image":{"@id":"https:\/\/www.formatsoftware.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/format-software-service-gmbh?originalSubdomain=de","https:\/\/www.xing.com\/pages\/formatsoftwareservicegmbh","https:\/\/www.youtube.com\/@FORMATSoftwareServiceGmbH"]}]}},"_links":{"self":[{"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/pages\/1517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/comments?post=1517"}],"version-history":[{"count":12,"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/pages\/1517\/revisions"}],"predecessor-version":[{"id":3526,"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/pages\/1517\/revisions\/3526"}],"wp:attachment":[{"href":"https:\/\/www.formatsoftware.de\/de\/wp-json\/wp\/v2\/media?parent=1517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}